{"id":42044,"date":"2019-04-16T10:08:06","date_gmt":"2019-04-16T08:08:06","guid":{"rendered":"https:\/\/www.traxco.es\/blog\/?p=42044"},"modified":"2025-12-19T07:56:27","modified_gmt":"2025-12-19T06:56:27","slug":"higroconvectores-knapen","status":"publish","type":"post","link":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen","title":{"rendered":"C\u00f3mo instalar higroconvectores knapen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"42044\" class=\"elementor elementor-42044\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48a4a430 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48a4a430\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-100cc50\" data-id=\"100cc50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31b58f2a elementor-widget elementor-widget-text-editor\" data-id=\"31b58f2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"alignright\" title=\"cartuchos higroconvectores Knapen\" src=\"\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-knapen.jpg\" alt=\"higroconvectores Knapen\" width=\"380\" \/>\n<p>La humedad presente en las partes bajas de los muros no es m\u00e1s que vapor de agua que se eleva por capilaridad desde el subsuelo a trav\u00e9s de los ladrillos, adobes, cemento, piedra o incluso por la madera. Este vapor de agua\u00a0va subiendo con una presi\u00f3n aproximada de una atm\u00f3sfera hasta una altura m\u00e1xima de 150 cent\u00edmetros desde el nivel del suelo, luego intenta salir, hinchando la pintura, liberando salitre y desmoronando el yeso.\u00a0Si no se aplica una soluci\u00f3n a estos problemas, el ladrillo termina desprendi\u00e9ndose y creando da\u00f1os en la mamposter\u00eda.<\/p>\n<p>En los casos de renovaci\u00f3n de edificios antiguos, se\u00a0construyen espacios de ventilaci\u00f3n, radiadores y ventanas que no exist\u00edan, pero las humedades aumentan o se repiten debido a la diferencia de temperatura entre el subsuelo y la mamposter\u00eda. Para poder eliminar la humedad, se debe permitir que el vapor de agua salga fuera de la pared evitando el desgaste interno, los abultamientos antiest\u00e9ticos y la creaci\u00f3n de un ambiente insalubre.<\/p>\n<p><strong>Instalar higroconvectores knapen<\/strong> es el \u00fanico sistema efectivo para cortar el ascenso de la humedad en los muros.<\/p>\n\n<h2>\u00bfC\u00f3mo funcionan los higroconvectores knapen?<\/h2>\n<p>Su funcionamiento est\u00e1 inspirado en los viejos sifones atmosf\u00e9ricos de ladrillo REMM, todav\u00eda visibles en iglesias y monumentos, pero a diferencia de aquellos, estos est\u00e1n fabricados en pl\u00e1stico antiest\u00e1tico.<\/p>\n<p>El cartucho especial antihumedad o <em>higroconvector<\/em>, ha sido dise\u00f1ado para eliminar la humedad capilar, se basa en el intercambio de calor entre la temperatura de dentro de la pared y el aire ambiente.\n<strong>Los higroconvectores knapen crean una circulaci\u00f3n natural de aire<\/strong> en la pared en la que se inserta, el aire seco sube (l\u00ednea roja) y el aire h\u00famedo baja (l\u00ednea azul), sec\u00e1ndola para siempre.<\/p>\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-42092\" title=\"as\u00ed funcionan los higroconvectores\" src=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/como-funcionan-los-higroconvectores.jpg\" alt=\"c\u00f3mo funcionan los higroconvectores\" width=\"100%\" srcset=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/como-funcionan-los-higroconvectores.jpg 582w, https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/como-funcionan-los-higroconvectores-380x131.jpg 380w, https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/como-funcionan-los-higroconvectores-575x198.jpg 575w, https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/como-funcionan-los-higroconvectores-300x104.jpg 300w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/>\n<p>Gracias a su facilidad de aplicaci\u00f3n, el cartucho higroconvector no requiere de instaladores profesionales y se puede colocar interna o externamente al muro. Para la instalaci\u00f3n es suficiente con hacer un agujero en la pared con un di\u00e1metro de 18 mm y dos tercios del espesor de la pared; el orificio debe realizarse siguiendo la inclinaci\u00f3n desde la parte inferior hacia arriba de aproximadamente 25-30 grados.<\/p>\n<p>Los <strong>higroconvectores knapen<\/strong>\u00a0se deben fijar en la pared con la aplicaci\u00f3n sobre la cabeza del cartucho de un poco de silicona, relleno de yeso o pegamento para baldosas. El agujero debe realizarse a una altura de 18-22 cm del nivel de suelo.<\/p>\n<p>Si la\u00a0pared tiene un espesor de 40 cm como m\u00e1ximo, basta con colocar una fila, <strong>separando los\u00a0cartuchos antihumedad 15 cent\u00edmetros<\/strong> entre s\u00ed.\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-42095\" title=\"higroconvectores instalacion de una fila\" src=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-instalacion.jpg\" alt=\"higroconvectores instalacion\" width=\"100%\" srcset=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-instalacion.jpg 582w, https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-instalacion-380x91.jpg 380w, https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-instalacion-300x72.jpg 300w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><\/p>\n<p>En el caso de una pared de m\u00e1s de 40 cm de espesor, se requiere una segunda fila a 10-12 cent\u00edmetros de la primera, con los cartuchos distribuidos a tresbolillo y a una distancia de 20 cm entre un cartucho y otro.\n<img decoding=\"async\" class=\"aligncenter size-full wp-image-42097\" title=\"dos filas de higroconvectores\" src=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-instalacion-dos-filas.jpg\" alt=\"higroconvectores instalacion de dos filas\" width=\"100%\" srcset=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-instalacion-dos-filas.jpg 582w, https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-instalacion-dos-filas-380x114.jpg 380w, https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-instalacion-dos-filas-300x90.jpg 300w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a6d136 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a6d136\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df7727c\" data-id=\"df7727c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-606921e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"606921e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/tienda\/higroconvectores\" title=\"higroconvectores knapen\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comprar higroconvectores ahora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El cartucho de humedad crea una circulaci\u00f3n natural de aire sec\u00e1ndola de forma definitiva. Se coloca realizando un agujero de di\u00e1metro 18 mm con una profundidad de dos tercios del espesor de la pared e inclinaci\u00f3n hacia arriba.<\/p>\n","protected":false},"author":6,"featured_media":42154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[6],"tags":[386],"class_list":["post-42044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-productos-nuevos","tag-humedad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Higroconvectores knapen - Recomendaciones de instalaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Los higroconvectores knapen, el sistema m\u00e1s efectivo para cortar el ascenso de la humedad desde el subsuelo a trav\u00e9s del cemento, la piedra...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Higroconvectores knapen - Recomendaciones de instalaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Los higroconvectores knapen, el sistema m\u00e1s efectivo para cortar el ascenso de la humedad desde el subsuelo a trav\u00e9s del cemento, la piedra...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de Traxco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Traxco.Riego.Pivot\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-16T08:08:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T06:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-knapen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cort\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@traxco\" \/>\n<meta name=\"twitter:site\" content=\"@traxco\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cort\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Higroconvectores knapen - Recomendaciones de instalaci\u00f3n","description":"Los higroconvectores knapen, el sistema m\u00e1s efectivo para cortar el ascenso de la humedad desde el subsuelo a trav\u00e9s del cemento, la piedra...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen","og_locale":"es_ES","og_type":"article","og_title":"Higroconvectores knapen - Recomendaciones de instalaci\u00f3n","og_description":"Los higroconvectores knapen, el sistema m\u00e1s efectivo para cortar el ascenso de la humedad desde el subsuelo a trav\u00e9s del cemento, la piedra...","og_url":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen","og_site_name":"El Blog de Traxco","article_publisher":"https:\/\/www.facebook.com\/Traxco.Riego.Pivot","article_published_time":"2019-04-16T08:08:06+00:00","article_modified_time":"2025-12-19T06:56:27+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-knapen.jpg","type":"image\/jpeg"}],"author":"Cort\u00e9s","twitter_card":"summary_large_image","twitter_creator":"@traxco","twitter_site":"@traxco","twitter_misc":{"Escrito por":"Cort\u00e9s","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen#article","isPartOf":{"@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen"},"author":{"name":"Cort\u00e9s","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/person\/877b26f904e3fc5d00613ca3aab84766"},"headline":"C\u00f3mo instalar higroconvectores knapen","datePublished":"2019-04-16T08:08:06+00:00","dateModified":"2025-12-19T06:56:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen"},"wordCount":496,"commentCount":22,"publisher":{"@id":"https:\/\/www.traxco.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen#primaryimage"},"thumbnailUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-knapen.jpg","keywords":["humedad"],"articleSection":["Productos nuevos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen","url":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen","name":"Higroconvectores knapen - Recomendaciones de instalaci\u00f3n","isPartOf":{"@id":"https:\/\/www.traxco.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen#primaryimage"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen#primaryimage"},"thumbnailUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-knapen.jpg","datePublished":"2019-04-16T08:08:06+00:00","dateModified":"2025-12-19T06:56:27+00:00","description":"Los higroconvectores knapen, el sistema m\u00e1s efectivo para cortar el ascenso de la humedad desde el subsuelo a trav\u00e9s del cemento, la piedra...","breadcrumb":{"@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen#primaryimage","url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-knapen.jpg","contentUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/04\/higroconvectores-knapen.jpg","width":300,"height":300,"caption":"higroconvectores Knapen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.traxco.es\/blog\/productos-nuevos\/higroconvectores-knapen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio &gt; Blog","item":"https:\/\/www.traxco.es\/"},{"@type":"ListItem","position":2,"name":"Productos nuevos","item":"https:\/\/www.traxco.es\/blog\/categorias\/productos-nuevos"},{"@type":"ListItem","position":3,"name":"C\u00f3mo instalar higroconvectores knapen"}]},{"@type":"WebSite","@id":"https:\/\/www.traxco.es\/blog\/#website","url":"https:\/\/www.traxco.es\/blog\/","name":"El Blog de Traxco","description":"Agricultura y Riego","publisher":{"@id":"https:\/\/www.traxco.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.traxco.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.traxco.es\/blog\/#organization","name":"Traxco","url":"https:\/\/www.traxco.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2023\/06\/cropped-traxco.png","contentUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2023\/06\/cropped-traxco.png","width":198,"height":39,"caption":"Traxco"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Traxco.Riego.Pivot","https:\/\/x.com\/traxco"]},{"@type":"Person","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/person\/877b26f904e3fc5d00613ca3aab84766","name":"Cort\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c9d679a5d81942e5b1e70bfc7bf0e776f9fb82137dab07df03453b2223263ccc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9d679a5d81942e5b1e70bfc7bf0e776f9fb82137dab07df03453b2223263ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9d679a5d81942e5b1e70bfc7bf0e776f9fb82137dab07df03453b2223263ccc?s=96&d=mm&r=g","caption":"Cort\u00e9s"},"description":"Experto en riego mecanizado, con una dilatada experiencia de m\u00e1s de 50 a\u00f1os en el sector. Su paso por Agrar le aport\u00f3 un amplio bagaje en toda la cadena de producci\u00f3n agr\u00edcola, (semillas, fertilizantes, riegos, maquinaria\u2026). Pionero en la introducci\u00f3n de Pivots de riego en Espa\u00f1a a trav\u00e9s de compa\u00f1\u00edas internacionales l\u00edderes como Valmont y Lockwood. Fund\u00f3 la empresa Traxco en 1991 para dar servicio en la distribuci\u00f3n de recambios y componentes originales para todos los fabricantes de Pivot, respaldando d\u00eda a d\u00eda en la instalaci\u00f3n y mantenimiento de estos y otros equipos de riego. Comprometido en concienciar y asesorar a los dem\u00e1s profesionales del sector, difundiendo las mejores pr\u00e1cticas y productos que ayuden a incrementar la rentabilidad de las explotaciones.","sameAs":["https:\/\/www.traxco.es\/"],"url":"https:\/\/www.traxco.es\/blog\/author\/cortes"}]}},"_links":{"self":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/42044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/comments?post=42044"}],"version-history":[{"count":57,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/42044\/revisions"}],"predecessor-version":[{"id":55125,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/42044\/revisions\/55125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/media\/42154"}],"wp:attachment":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/media?parent=42044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/categories?post=42044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/tags?post=42044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}