{"id":41675,"date":"2019-02-14T11:21:43","date_gmt":"2019-02-14T09:21:43","guid":{"rendered":"https:\/\/www.traxco.es\/blog\/?p=41675"},"modified":"2025-12-19T07:56:28","modified_gmt":"2025-12-19T06:56:28","slug":"reparacion-de-tuberias-sin-zanja","status":"publish","type":"post","link":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja","title":{"rendered":"Reparaci\u00f3n de tuber\u00edas sin zanja"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright\" title=\"reparaci\u00f3n de tuber\u00edas sin zanja ni obras\" src=\"\/blog\/wp-content\/uploads\/2019\/02\/tuberia-sin-zanja.jpg\" alt=\"reparaci\u00f3n de tuber\u00edas sin zanja\" width=\"380\" \/><\/p>\n<p>Los trabajos de mantenimiento en conducciones de presi\u00f3n o gravedad, requieren de reparaciones y en ocasiones, de la sustituci\u00f3n de las tuber\u00edas defectuosas por diversos motivos.<\/p>\n<h2>Equipo neum\u00e1tico para reparaci\u00f3n de tuber\u00edas sin zanja<\/h2>\n<p>Presentamos la soluci\u00f3n perfecta, r\u00e1pida, sencilla y econ\u00f3mica, para efectuar el saneamiento y la <strong>reparaci\u00f3n de tuber\u00edas sin zanja<\/strong> en conductos de agua de riego, de agua potable, gas y aguas residuales, de hasta un m\u00e1ximo de 300 metros de longitud, en subsuelos delicados o\u00a0con proximidad a otras tuber\u00edas o cables el\u00e9ctricos, as\u00ed como bajo edificios o carreteras.<\/p>\n<p>Se trata de un equipo de martillo neum\u00e1tico modificado y accionado por aire comprimido que es introducido en las tuber\u00edas antiguas de gres, fibrocemento, hierro gris, pl\u00e1stico u hormig\u00f3n, con di\u00e1metros de entre 50 y 1200 mil\u00edmetros. A medida que avanza, guiado por la fuerza de tiro de un cabrestante (que ayuda en el arrastre y garantiza una direcci\u00f3n segura por el interior del trazado), rompe, tritura y compacta los trozos rotos de forma radial haciendo que penetren en el terreno. Al mismo tiempo, ensancha el di\u00e1metro de la perforaci\u00f3n para la tuber\u00eda nueva.<\/p>\n<p>Este equipo para la <strong>reparaci\u00f3n de tuber\u00edas sin obras\u00a0<\/strong>(que incluso se puede adaptar a ligeras curvaturas) est\u00e1 compuesto por una plataforma de tiro con cilindros hidr\u00e1ulicos, una estaci\u00f3n hidr\u00e1ulica, barras de tiro (de enganche r\u00e1pido) patentadas, cuchillas de corte y expansores de diferentes di\u00e1metros. El sistema permite insertar tuber\u00edas de sustituci\u00f3n nuevas (de pl\u00e1stico, metal, fibra de vidrio, gres, etc.), con un di\u00e1metro menor, igual, o incluso mayor a la tuber\u00eda antigua, con rendimientos desde 150 a 300 metros por d\u00eda y ahorrando un 50% en costes en comparaci\u00f3n con las t\u00e9cnicas tradicionales.<\/p>\n<p>Despu\u00e9s de introducir las barras en la tuber\u00eda antigua, se conectan a \u00e9stas los accesorios de corte y de expansi\u00f3n, adem\u00e1s de la nueva tuber\u00eda a instalar. Al ir extrayendo las barras, la cuchilla en el cabezal corta la tuber\u00eda antigua. El elemento de expansi\u00f3n colocado detr\u00e1s, ampl\u00eda la perforaci\u00f3n y alisa o comprime las paredes de los trazados de tuber\u00edas existentes. La tuber\u00eda nueva puede ser continua y se introduce directamente, o formada por varios tramos que se van soldando al tiempo que se insertan.<\/p>\n<h3>Motivos para la reparaci\u00f3n de tuber\u00edas sin zanja<\/h3>\n<ul>\n<li>Fugas de agua.<\/li>\n<li>P\u00e9rdidas de aguas residuales que contaminan las aguas subterr\u00e1neas.<\/li>\n<li>Penetraci\u00f3n de aguas subterr\u00e1neas en la l\u00ednea de abastecimiento.<\/li>\n<li>Exceso o defecto de capacidad de la red de tuber\u00edas.<\/li>\n<\/ul>\n<h3>Da\u00f1os caracter\u00edsticos en tuber\u00edas enterradas<\/h3>\n<ul>\n<li>Grietas.<\/li>\n<li>Incrustaciones.<\/li>\n<li>Penetraci\u00f3n de ra\u00edces.<\/li>\n<li>Desalineaci\u00f3n.<\/li>\n<li>Desviaciones por movimientos del terreno.<\/li>\n<li>Abertura de los manguitos.<\/li>\n<li>Desgaste mec\u00e1nico de las tuber\u00edas.<\/li>\n<li>Taponamientos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Equipos neum\u00e1ticos con cabezales especiales accionados por aire comprimido, que permiten sustituir r\u00e1pida y f\u00e1cilmente hasta 300 m de tuber\u00eda enterrada de presi\u00f3n o de gravedad con un di\u00e1metro de 50 hasta 1200 mm sin la necesidad de practicar ning\u00fan tipo de zanja en el terreno.<\/p>\n","protected":false},"author":6,"featured_media":41756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[294],"tags":[749,270],"class_list":["post-41675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia-del-riego","tag-reparar-tuberias","tag-tuberias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Equipo neum\u00e1tico para la reparaci\u00f3n de tuber\u00edas sin zanja<\/title>\n<meta name=\"description\" content=\"Soluci\u00f3n r\u00e1pida, sencilla y econ\u00f3mica para la reparaci\u00f3n de tuber\u00edas sin zanja en conductos de agua de riego o potable, aguas residuales y gas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equipo neum\u00e1tico para la reparaci\u00f3n de tuber\u00edas sin zanja\" \/>\n<meta property=\"og:description\" content=\"Soluci\u00f3n r\u00e1pida, sencilla y econ\u00f3mica para la reparaci\u00f3n de tuber\u00edas sin zanja en conductos de agua de riego o potable, aguas residuales y gas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de Traxco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Traxco.Riego.Pivot\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-14T09:21:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T06:56:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/02\/tuberia-sin-zanja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cort\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@traxco\" \/>\n<meta name=\"twitter:site\" content=\"@traxco\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cort\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equipo neum\u00e1tico para la reparaci\u00f3n de tuber\u00edas sin zanja","description":"Soluci\u00f3n r\u00e1pida, sencilla y econ\u00f3mica para la reparaci\u00f3n de tuber\u00edas sin zanja en conductos de agua de riego o potable, aguas residuales y gas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja","og_locale":"es_ES","og_type":"article","og_title":"Equipo neum\u00e1tico para la reparaci\u00f3n de tuber\u00edas sin zanja","og_description":"Soluci\u00f3n r\u00e1pida, sencilla y econ\u00f3mica para la reparaci\u00f3n de tuber\u00edas sin zanja en conductos de agua de riego o potable, aguas residuales y gas.","og_url":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja","og_site_name":"El Blog de Traxco","article_publisher":"https:\/\/www.facebook.com\/Traxco.Riego.Pivot","article_published_time":"2019-02-14T09:21:43+00:00","article_modified_time":"2025-12-19T06:56:28+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/02\/tuberia-sin-zanja.jpg","type":"image\/jpeg"}],"author":"Cort\u00e9s","twitter_card":"summary_large_image","twitter_creator":"@traxco","twitter_site":"@traxco","twitter_misc":{"Escrito por":"Cort\u00e9s","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja#article","isPartOf":{"@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja"},"author":{"name":"Cort\u00e9s","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/person\/877b26f904e3fc5d00613ca3aab84766"},"headline":"Reparaci\u00f3n de tuber\u00edas sin zanja","datePublished":"2019-02-14T09:21:43+00:00","dateModified":"2025-12-19T06:56:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja"},"wordCount":500,"commentCount":2,"publisher":{"@id":"https:\/\/www.traxco.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja#primaryimage"},"thumbnailUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/02\/tuberia-sin-zanja.jpg","keywords":["reparar tuberias","tuber\u00edas"],"articleSection":["Tecnolog\u00eda del riego"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja","url":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja","name":"Equipo neum\u00e1tico para la reparaci\u00f3n de tuber\u00edas sin zanja","isPartOf":{"@id":"https:\/\/www.traxco.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja#primaryimage"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja#primaryimage"},"thumbnailUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/02\/tuberia-sin-zanja.jpg","datePublished":"2019-02-14T09:21:43+00:00","dateModified":"2025-12-19T06:56:28+00:00","description":"Soluci\u00f3n r\u00e1pida, sencilla y econ\u00f3mica para la reparaci\u00f3n de tuber\u00edas sin zanja en conductos de agua de riego o potable, aguas residuales y gas.","breadcrumb":{"@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja#primaryimage","url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/02\/tuberia-sin-zanja.jpg","contentUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2019\/02\/tuberia-sin-zanja.jpg","width":300,"height":300,"caption":"reparaci\u00f3n de tuber\u00edas sin zanja"},{"@type":"BreadcrumbList","@id":"https:\/\/www.traxco.es\/blog\/tecnologia-del-riego\/reparacion-de-tuberias-sin-zanja#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio &gt; Blog","item":"https:\/\/www.traxco.es\/"},{"@type":"ListItem","position":2,"name":"Tecnolog\u00eda del riego","item":"https:\/\/www.traxco.es\/blog\/categorias\/tecnologia-del-riego"},{"@type":"ListItem","position":3,"name":"Reparaci\u00f3n de tuber\u00edas sin zanja"}]},{"@type":"WebSite","@id":"https:\/\/www.traxco.es\/blog\/#website","url":"https:\/\/www.traxco.es\/blog\/","name":"El Blog de Traxco","description":"Agricultura y Riego","publisher":{"@id":"https:\/\/www.traxco.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.traxco.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.traxco.es\/blog\/#organization","name":"Traxco","url":"https:\/\/www.traxco.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2023\/06\/cropped-traxco.png","contentUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2023\/06\/cropped-traxco.png","width":198,"height":39,"caption":"Traxco"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Traxco.Riego.Pivot","https:\/\/x.com\/traxco"]},{"@type":"Person","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/person\/877b26f904e3fc5d00613ca3aab84766","name":"Cort\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c9d679a5d81942e5b1e70bfc7bf0e776f9fb82137dab07df03453b2223263ccc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9d679a5d81942e5b1e70bfc7bf0e776f9fb82137dab07df03453b2223263ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9d679a5d81942e5b1e70bfc7bf0e776f9fb82137dab07df03453b2223263ccc?s=96&d=mm&r=g","caption":"Cort\u00e9s"},"description":"Experto en riego mecanizado, con una dilatada experiencia de m\u00e1s de 50 a\u00f1os en el sector. Su paso por Agrar le aport\u00f3 un amplio bagaje en toda la cadena de producci\u00f3n agr\u00edcola, (semillas, fertilizantes, riegos, maquinaria\u2026). Pionero en la introducci\u00f3n de Pivots de riego en Espa\u00f1a a trav\u00e9s de compa\u00f1\u00edas internacionales l\u00edderes como Valmont y Lockwood. Fund\u00f3 la empresa Traxco en 1991 para dar servicio en la distribuci\u00f3n de recambios y componentes originales para todos los fabricantes de Pivot, respaldando d\u00eda a d\u00eda en la instalaci\u00f3n y mantenimiento de estos y otros equipos de riego. Comprometido en concienciar y asesorar a los dem\u00e1s profesionales del sector, difundiendo las mejores pr\u00e1cticas y productos que ayuden a incrementar la rentabilidad de las explotaciones.","sameAs":["https:\/\/www.traxco.es\/"],"url":"https:\/\/www.traxco.es\/blog\/author\/cortes"}]}},"_links":{"self":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/41675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/comments?post=41675"}],"version-history":[{"count":42,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/41675\/revisions"}],"predecessor-version":[{"id":55183,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/41675\/revisions\/55183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/media\/41756"}],"wp:attachment":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/media?parent=41675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/categories?post=41675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/tags?post=41675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}