{"id":12214,"date":"2012-07-30T18:46:07","date_gmt":"2012-07-30T16:46:07","guid":{"rendered":"https:\/\/www.traxco.es\/blog\/?p=12214"},"modified":"2025-12-19T07:51:18","modified_gmt":"2025-12-19T06:51:18","slug":"aumentar-rentabilidad-del-olivar","status":"publish","type":"post","link":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar","title":{"rendered":"T\u00e9cnicas para aumentar la rentabilidad del olivar"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright\" title=\"rentabilidad del olivar\" src=\"\/blog\/wp-content\/uploads\/2012\/07\/olivares.jpg\" alt=\"olivar\" width=\"380\" \/><\/p>\n<p>Aunque en Andaluc\u00eda <strong>los olivares<\/strong> son ya de edad avanzada y hay bajas densidades de plantaci\u00f3n, en esta Comunidad Aut\u00f3noma es en la que m\u00e1s aceite y aceitunas se producen de toda Espa\u00f1a (se cultivan m\u00e1s del 60% de los 2,5 millones de hect\u00e1reas totales).<br \/>\nAdem\u00e1s, predomina el secano, hay dependencia en la mano de obra y los costes productivos son elevados. Por todo ello, la cuenta de resultados olivarera presenta resultados negativos.<\/p>\n<p>El <strong>r\u00e1pido desarrollo del olivar<\/strong> en otros pa\u00edses mediterr\u00e1neos durante las \u00faltimas d\u00e9cadas nos est\u00e1 llevando a p\u00e9rdidas de competitividad cada vez m\u00e1s notables. Necesitamos mejorar nuestra producci\u00f3n por superficie, en cantidad y calidad, empleando unas t\u00e9cnicas que mejoren la producci\u00f3n, optimizando el medio productivo y mejorando la eficiencia de los factores de producci\u00f3n.<\/p>\n<p>Para reducir notablemente los costes de producci\u00f3n, una acci\u00f3n que se convierte en obligatoria es la mecanizaci\u00f3n de determinadas pr\u00e1cticas como la poda o la recolecci\u00f3n.<\/p>\n<p>Es necesario aumentar los ingresos, mejorando la producci\u00f3n y la calidad de la misma. Una forma eficaz, es aumentando la densidad de plantaci\u00f3n. Hay diversos estudios que demuestran que el aumento de 100 a 300 olivos\/ha consigue unos aumentos de producci\u00f3n importantes, dependiendo del volumen de la copa. Este aumento se ha de realizar siempre con un manejo agron\u00f3micamente sostenible, y obteniendo \u00e1rboles individuales.<\/p>\n<h2>Riego y fertilizaci\u00f3n del olivar<\/h2>\n<p>El agua es el principal factor limitante de la producci\u00f3n. El empleo de <strong>riegos<\/strong> incluso deficitarios, est\u00e1 dando muy buenos resultados, haciendo posible la reducci\u00f3n del agua aportada, y aumentando la eficacia de este recurso. Los estudios demuestran que con la <em>puesta de riego<\/em> en una plantaci\u00f3n es posible duplicar la producci\u00f3n.<\/p>\n<p>La <strong>fertilizaci\u00f3n<\/strong> se hace a menudo de forma an\u00e1rquica y arbitraria. El an\u00e1lisis del suelo es fundamental para establecer los protocolos de fertilizaci\u00f3n. En olivares poco productivos podr\u00eda evitarse esta fertilizaci\u00f3n, sin embargo, en <em>olivares de riego<\/em> con altas producciones, se hace necesario el uso de la <strong><a title=\"inyectores de fertilizantes\" href=\"https:\/\/www.traxco.es\/productos\/otros-componentes\/inyectores-de-fertilizante\/\" target=\"_blank\" rel=\"noopener\">fertilizaci\u00f3n mediante inyectores hidr\u00e1ulicos o el\u00e9ctricos<\/a><\/strong>.<\/p>\n<p>En ocasiones, la falta de respuesta a la fertilizaci\u00f3n se debe al bloqueo de otros elementos en el suelo. Por ejemplo, el bloqueo del hierro hace que los \u00e1rboles presenten s\u00edntomas de clorosis f\u00e9rrica. La cantidad de hierro que consume la planta es peque\u00f1a, pero muy importante.<\/p>\n<h3>Recolecci\u00f3n<\/h3>\n<p>La mecanizaci\u00f3n de la recolecci\u00f3n requiere una inversi\u00f3n, pero es fundamental para rentabilizar el cultivo. En un <em>olivar<\/em> con un nivel de producci\u00f3n medio-bajo, los costes var\u00edan entre 0,276 y 0,293 \u20ac\/kg; mientras que en un olivar intensivo mecanizado con sistemas de recolecci\u00f3n de paraguas invertido, los costes oscilan entre los 0,071 y 0,106 \u20ac\/kg.<\/p>\n<h3>Poda y manejo del suelo<\/h3>\n<p>La poda necesita mano de obra especializada, y \u00e9sta escasea. La mecanizaci\u00f3n de la poda est\u00e1 dando resultados muy positivos. Si se realiza la poda mecanizada, el agricultor es capaz de obtener la misma producci\u00f3n, o incluso superior, que si se realiza de forma manual. El empleo de sistemas de manejo del suelo tambi\u00e9n puede representar una mejora de la producci\u00f3n. La p\u00e9rdida de suelo es el principal problema de las zonas \u00e1ridas, <strong>donde se cultiva el olivo<\/strong>.<\/p>\n<h3>Subproductos del olivar<\/h3>\n<p>La <a title=\"almohadas con huesos de aceituna\" href=\"https:\/\/www.traxco.es\/blog\/noticias-agricolas\/aprovechamiento-integro-de-produccion\" target=\"_blank\" rel=\"noopener\">reutilizaci\u00f3n de los subproductos del olivar<\/a>, supone el cierre del cultivo y una ayuda econ\u00f3mica. La le\u00f1a de poda picada y el alperujo, son una fuente de elementos nutricionales y un recurso de materia org\u00e1nica para mejorar los suelos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La densidad de cultivo, el manejo del suelo, el riego, fertilizaci\u00f3n, la poda y de la recolecci\u00f3n, son b\u00e1sicos para mejorar la rentabilidad del olivar. Para poder aumentar los ingresos, es necesario mejorar los procesos de producci\u00f3n.<\/p>\n","protected":false},"author":6,"featured_media":12274,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[32],"tags":[165,610,694,447,609],"class_list":["post-12214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produccion-agricola","tag-agua","tag-fertilizacion","tag-inyectora-de-fertilizante","tag-olivo","tag-riegos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00e9cnicas agron\u00f3micas para aumentar la rentabilidad del olivar<\/title>\n<meta name=\"description\" content=\"C\u00f3mo mejorar la rentabilidad del olivar: manejo de suelos, riego, fertilizaci\u00f3n, densidad de cultivo, mecanizaci\u00f3n de la poda y recolecci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9cnicas agron\u00f3micas para aumentar la rentabilidad del olivar\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo mejorar la rentabilidad del olivar: manejo de suelos, riego, fertilizaci\u00f3n, densidad de cultivo, mecanizaci\u00f3n de la poda y recolecci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de Traxco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Traxco.Riego.Pivot\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-30T16:46:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T06:51:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2012\/07\/olivares.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cort\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@traxco\" \/>\n<meta name=\"twitter:site\" content=\"@traxco\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cort\u00e9s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9cnicas agron\u00f3micas para aumentar la rentabilidad del olivar","description":"C\u00f3mo mejorar la rentabilidad del olivar: manejo de suelos, riego, fertilizaci\u00f3n, densidad de cultivo, mecanizaci\u00f3n de la poda y recolecci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9cnicas agron\u00f3micas para aumentar la rentabilidad del olivar","og_description":"C\u00f3mo mejorar la rentabilidad del olivar: manejo de suelos, riego, fertilizaci\u00f3n, densidad de cultivo, mecanizaci\u00f3n de la poda y recolecci\u00f3n","og_url":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar","og_site_name":"El Blog de Traxco","article_publisher":"https:\/\/www.facebook.com\/Traxco.Riego.Pivot","article_published_time":"2012-07-30T16:46:07+00:00","article_modified_time":"2025-12-19T06:51:18+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2012\/07\/olivares.jpg","type":"image\/jpeg"}],"author":"Cort\u00e9s","twitter_card":"summary_large_image","twitter_creator":"@traxco","twitter_site":"@traxco","twitter_misc":{"Escrito por":"Cort\u00e9s","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar#article","isPartOf":{"@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar"},"author":{"name":"Cort\u00e9s","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/person\/877b26f904e3fc5d00613ca3aab84766"},"headline":"T\u00e9cnicas para aumentar la rentabilidad del olivar","datePublished":"2012-07-30T16:46:07+00:00","dateModified":"2025-12-19T06:51:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar"},"wordCount":618,"commentCount":2,"publisher":{"@id":"https:\/\/www.traxco.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar#primaryimage"},"thumbnailUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2012\/07\/olivares.jpg","keywords":["agua","fertilizaci\u00f3n","inyectora de fertilizante","olivo","riegos"],"articleSection":["Producci\u00f3n agr\u00edcola"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar","url":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar","name":"T\u00e9cnicas agron\u00f3micas para aumentar la rentabilidad del olivar","isPartOf":{"@id":"https:\/\/www.traxco.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar#primaryimage"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar#primaryimage"},"thumbnailUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2012\/07\/olivares.jpg","datePublished":"2012-07-30T16:46:07+00:00","dateModified":"2025-12-19T06:51:18+00:00","description":"C\u00f3mo mejorar la rentabilidad del olivar: manejo de suelos, riego, fertilizaci\u00f3n, densidad de cultivo, mecanizaci\u00f3n de la poda y recolecci\u00f3n","breadcrumb":{"@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar#primaryimage","url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2012\/07\/olivares.jpg","contentUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2012\/07\/olivares.jpg","width":300,"height":300,"caption":"olivar"},{"@type":"BreadcrumbList","@id":"https:\/\/www.traxco.es\/blog\/produccion-agricola\/aumentar-rentabilidad-del-olivar#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio &gt; Blog","item":"https:\/\/www.traxco.es\/"},{"@type":"ListItem","position":2,"name":"Producci\u00f3n agr\u00edcola","item":"https:\/\/www.traxco.es\/blog\/categorias\/produccion-agricola"},{"@type":"ListItem","position":3,"name":"T\u00e9cnicas para aumentar la rentabilidad del olivar"}]},{"@type":"WebSite","@id":"https:\/\/www.traxco.es\/blog\/#website","url":"https:\/\/www.traxco.es\/blog\/","name":"El Blog de Traxco","description":"Agricultura y Riego","publisher":{"@id":"https:\/\/www.traxco.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.traxco.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.traxco.es\/blog\/#organization","name":"Traxco","url":"https:\/\/www.traxco.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2023\/06\/cropped-traxco.png","contentUrl":"https:\/\/www.traxco.es\/blog\/wp-content\/uploads\/2023\/06\/cropped-traxco.png","width":198,"height":39,"caption":"Traxco"},"image":{"@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Traxco.Riego.Pivot","https:\/\/x.com\/traxco"]},{"@type":"Person","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/person\/877b26f904e3fc5d00613ca3aab84766","name":"Cort\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.traxco.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c9d679a5d81942e5b1e70bfc7bf0e776f9fb82137dab07df03453b2223263ccc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9d679a5d81942e5b1e70bfc7bf0e776f9fb82137dab07df03453b2223263ccc?s=96&d=mm&r=g","caption":"Cort\u00e9s"},"description":"Experto en riego mecanizado, con una dilatada experiencia de m\u00e1s de 50 a\u00f1os en el sector. Su paso por Agrar le aport\u00f3 un amplio bagaje en toda la cadena de producci\u00f3n agr\u00edcola, (semillas, fertilizantes, riegos, maquinaria\u2026). Pionero en la introducci\u00f3n de Pivots de riego en Espa\u00f1a a trav\u00e9s de compa\u00f1\u00edas internacionales l\u00edderes como Valmont y Lockwood. Fund\u00f3 la empresa Traxco en 1991 para dar servicio en la distribuci\u00f3n de recambios y componentes originales para todos los fabricantes de Pivot, respaldando d\u00eda a d\u00eda en la instalaci\u00f3n y mantenimiento de estos y otros equipos de riego. Comprometido en concienciar y asesorar a los dem\u00e1s profesionales del sector, difundiendo las mejores pr\u00e1cticas y productos que ayuden a incrementar la rentabilidad de las explotaciones.","sameAs":["https:\/\/www.traxco.es\/"],"url":"https:\/\/www.traxco.es\/blog\/author\/cortes"}]}},"_links":{"self":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/12214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/comments?post=12214"}],"version-history":[{"count":4,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/12214\/revisions"}],"predecessor-version":[{"id":58877,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/posts\/12214\/revisions\/58877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/media\/12274"}],"wp:attachment":[{"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/media?parent=12214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/categories?post=12214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.traxco.es\/blog\/wp-json\/wp\/v2\/tags?post=12214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}